{"id":74,"date":"2016-08-29T22:32:01","date_gmt":"2016-08-29T21:32:01","guid":{"rendered":"https:\/\/dgd.es\/?page_id=74"},"modified":"2026-04-17T09:55:20","modified_gmt":"2026-04-17T08:55:20","slug":"maintenance","status":"publish","type":"page","link":"https:\/\/gdes.com\/wind\/fr\/maintenance\/","title":{"rendered":"Maintenance et  inspections"},"content":{"rendered":"<p>L&rsquo;objectif est d\u2019optimiser l&rsquo;entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d&rsquo;\u00e9nergie.&nbsp;<b>GDES Wind <\/b>poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n&rsquo;importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux de cordiste.<\/p>\n<h3>&nbsp;<\/h3>\n<h4 style=\"text-align: center;\">Sites de r\u00e9paration et de fabrication de GDES Wind en Espagne<\/h4>\n<hr>\n\n<h4 style=\"padding-left: 80px; text-align: center;\"><strong>Pontes de Garc\u00eda Rodr\u00edguez, Galicia<\/strong><\/h4>\n<table style=\"width: 100%; border-collapse: collapse; border-style: hidden;\" border=\"1\">\n<tbody>\n<tr style=\"height: 458px;\">\n<td style=\"width: 50%; height: 458px;\">\n<h4>&nbsp;<\/h4>\n<h4 style=\"padding-left: 70px;\">Extension de 15.000 m2&nbsp;<\/h4>\n<h4 style=\"padding-left: 70px;\">Atelier de 3.200 m2&nbsp;<\/h4>\n<h4 style=\"padding-left: 70px;\"><span style=\"font-family: inherit; font-size: inherit;\">Enti\u00e8rement \u00e9quip\u00e9s et climatis\u00e9<\/span><\/h4>\n<h4 style=\"padding-left: 70px;\">&nbsp;<\/h4>\n<\/td>\n<td style=\"width: 50%; height: 458px;\">\n<h4>&nbsp;<\/h4>\n<h4 style=\"padding-left: 70px;\">4 grues roulantes<\/h4>\n<h4 style=\"padding-left: 70px;\">Directement connect\u00e9 avec AG-64<\/h4>\n<h4 style=\"padding-left: 70px;\">30 minutes du port de Ferrol et 550 minutes de l&rsquo;a\u00e9roport de La Corogne ou de Santiago<\/h4>\n<p>&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\">Nos principaux services de maintenance et d&rsquo;inspection :<\/h4>\n<hr>\n<h4 style=\"text-align: left;\">&nbsp;<\/h4>\n<p><img decoding=\"async\" class=\"wp-image-4058 size-full alignright\" src=\"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/01\/GDES-WIND-logweb.png\" alt=\"\" width=\"202\" height=\"40\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<table style=\"height: 297px; border-style: hidden; width: 1020px;\" width=\"1013\">\n<tbody>\n<tr style=\"height: 23px;\">\n<td style=\"width: 1012.39px; height: 23px;\"><strong>Inspections pendant le processus de production<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 1012.39px; height: 24px;\"><strong>Inspections avant l&rsquo;assemblage<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 1012.39px; height: 24px;\"><strong>Inspections sur le terrain, \u00e0 partir du sol au moyen de t\u00e9lescopes<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 1012.39px; height: 24px;\"><strong>Inspections externes et internes en hauteur<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 1012.39px; height: 24px;\"><strong>Thermographie<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 1012.39px;\"><strong>R\u00e9parations sur le terrain<\/strong><strong><br \/>\n<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 1012.39px;\"><strong>R\u00e9parations dans l&rsquo;usine<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 1012.39px;\"><strong>Fourniture de mat\u00e9riaux et pi\u00e8ces<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"width: 1012.39px; height: 24px;\"><strong>Ultrasons (standard et phased-array)<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">&nbsp;<\/p>\n<h4 style=\"text-align: center;\"><a class=\"fasc-button fasc-size-large fasc-type-flat ico-fa fasc-ico-before fa-cloud-download\" style=\"background-color: #5ca2df; color: #ffffff;\" target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2026\/04\/Folleto-wind-A4.pdf\">T\u00e9l\u00e9charger le dossier d&rsquo;information<\/a><\/h4>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;objectif est d\u2019optimiser l&rsquo;entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d&rsquo;\u00e9nergie.&nbsp;GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n&rsquo;importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"Page-fullwidth.php","meta":{"footnotes":""},"class_list":["post-74","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"L&#039;objectif est d\u2019optimiser l&#039;entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d&#039;\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n&#039;importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gdes.com\/wind\/fr\/maintenance\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"GDES Wind -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Maintenance et inspections - GDES Wind\" \/>\n\t\t<meta property=\"og:description\" content=\"L&#039;objectif est d\u2019optimiser l&#039;entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d&#039;\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n&#039;importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gdes.com\/wind\/fr\/maintenance\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-08-29T21:32:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-04-17T08:55:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Maintenance et inspections - GDES Wind\" \/>\n\t\t<meta name=\"twitter:description\" content=\"L&#039;objectif est d\u2019optimiser l&#039;entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d&#039;\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n&#039;importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#listItem\",\"name\":\"Maintenance et  inspections\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#listItem\",\"position\":2,\"name\":\"Maintenance et  inspections\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/#organization\",\"name\":\"GDES Wind\",\"url\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gdes.com\\\/wind\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2021\\\/02\\\/cropped-GDES-WIND-LogoWeb-03.jpg\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#organizationLogo\",\"width\":217,\"height\":44},\"image\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#webpage\",\"url\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/\",\"name\":\"Maintenance et inspections - GDES Wind\",\"description\":\"L'objectif est d\\u2019optimiser l'entretien des pales, de minimiser les co\\u00fbts du cycle de vie et de permettre une meilleure production d'\\u00e9nergie. GDES Wind poss\\u00e8de une vaste exp\\u00e9rience et la capacit\\u00e9 de g\\u00e9rer n'importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/maintenance\\\/#breadcrumblist\"},\"datePublished\":\"2016-08-29T22:32:01+01:00\",\"dateModified\":\"2026-04-17T09:55:20+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/\",\"name\":\"GDES Wind\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/wind\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Maintenance et inspections - GDES Wind","description":"L'objectif est d\u2019optimiser l'entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d'\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n'importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux","canonical_url":"https:\/\/gdes.com\/wind\/fr\/maintenance\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gdes.com\/wind\/fr#listItem","position":1,"name":"Inicio","item":"https:\/\/gdes.com\/wind\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#listItem","name":"Maintenance et  inspections"}},{"@type":"ListItem","@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#listItem","position":2,"name":"Maintenance et  inspections","previousItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/wind\/fr#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/gdes.com\/wind\/fr\/#organization","name":"GDES Wind","url":"https:\/\/gdes.com\/wind\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg","@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#organizationLogo","width":217,"height":44},"image":{"@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#webpage","url":"https:\/\/gdes.com\/wind\/fr\/maintenance\/","name":"Maintenance et inspections - GDES Wind","description":"L'objectif est d\u2019optimiser l'entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d'\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n'importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/gdes.com\/wind\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/gdes.com\/wind\/fr\/maintenance\/#breadcrumblist"},"datePublished":"2016-08-29T22:32:01+01:00","dateModified":"2026-04-17T09:55:20+01:00"},{"@type":"WebSite","@id":"https:\/\/gdes.com\/wind\/fr\/#website","url":"https:\/\/gdes.com\/wind\/fr\/","name":"GDES Wind","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/gdes.com\/wind\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"GDES Wind -","og:type":"article","og:title":"Maintenance et inspections - GDES Wind","og:description":"L'objectif est d\u2019optimiser l'entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d'\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n'importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux","og:url":"https:\/\/gdes.com\/wind\/fr\/maintenance\/","og:image":"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg","og:image:secure_url":"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg","article:published_time":"2016-08-29T21:32:01+00:00","article:modified_time":"2026-04-17T08:55:20+00:00","twitter:card":"summary_large_image","twitter:title":"Maintenance et inspections - GDES Wind","twitter:description":"L'objectif est d\u2019optimiser l'entretien des pales, de minimiser les co\u00fbts du cycle de vie et de permettre une meilleure production d'\u00e9nergie. GDES Wind poss\u00e8de une vaste exp\u00e9rience et la capacit\u00e9 de g\u00e9rer n'importe quel type de dispositif de levage auxiliaire, et nos techniciens ont les certifications requises pour effectuer des travaux en hauteur dont les travaux","twitter:image":"https:\/\/gdes.com\/wind\/wp-content\/uploads\/sites\/10\/2021\/02\/cropped-GDES-WIND-LogoWeb-03.jpg"},"aioseo_meta_data":{"post_id":"74","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-01-23 14:05:26","updated":"2026-04-17 09:46:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gdes.com\/wind\/fr\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMaintenance et  inspections\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/gdes.com\/wind\/fr"},{"label":"Maintenance et  inspections","link":"https:\/\/gdes.com\/wind\/fr\/maintenance\/"}],"_links":{"self":[{"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/pages\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":237,"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/pages\/74\/revisions"}],"predecessor-version":[{"id":4623,"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/pages\/74\/revisions\/4623"}],"wp:attachment":[{"href":"https:\/\/gdes.com\/wind\/fr\/wp-json\/wp\/v2\/media?parent=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}