{"id":404352,"date":"2026-06-09T14:30:49","date_gmt":"2026-06-09T13:30:49","guid":{"rendered":"https:\/\/gdes.com\/corporate\/?p=404352"},"modified":"2026-06-09T14:45:57","modified_gmt":"2026-06-09T13:45:57","slug":"gdes-celebro-1000-dias-de-trabajo-seguro-en-iter","status":"publish","type":"post","link":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/","title":{"rendered":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER"},"content":{"rendered":"<p>GDES celebr\u00f3 un hito muy significativo en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas. Un logro que reflej\u00f3 el compromiso diario del equipo con un objetivo constante: construir entornos de trabajo cada vez m\u00e1s seguros.<\/p>\n<p><!--more--><\/p>\n<p>Porque la seguridad no es un resultado puntual, sino un proceso compartido, este hito representa 1.000 d\u00edas construyendo seguridad juntos en ITER, a trav\u00e9s de la implicaci\u00f3n de todos los profesionales y del trabajo coordinado con el cliente. \u00a0En este sentido, la celebraci\u00f3n cont\u00f3 con el apoyo y la presencia de los representantes de nuestro contrato con ITER Organization, de antiguos clientes como F4E, as\u00ed como de otros clientes como Monsud, quienes trasladaron su felicitaci\u00f3n al equipo por el trabajo realizado.<\/p>\n<p>Para GDES, la seguridad es un principio que gu\u00eda cada intervenci\u00f3n. La <strong>Cultura de Seguridad<\/strong> es uno de los ejes estrat\u00e9gicos del Grupo, y se trabaj\u00f3 de forma continua para reforzarla mediante iniciativas y pol\u00edticas orientadas a tres objetivos fundamentales: garantizar la seguridad en todas las actuaciones, mejorar la calidad del servicio evitando la repetici\u00f3n de trabajos y mantener la siniestralidad laboral y los incidentes ambientales en niveles cero. En definitiva, <strong>la seguridad como compromiso diario<\/strong>, m\u00e1s all\u00e1 de cualquier cifra concreta.<\/p>\n<p>Este resultado puso en valor la implicaci\u00f3n colectiva del equipo, la eficacia de las medidas preventivas y el esfuerzo sostenido por reducir el error humano en todas las operaciones.<\/p>\n<p>Para conmemorar este logro, el pasado <strong>13 de mayo<\/strong> se organiz\u00f3 una jornada de celebraci\u00f3n en las oficinas de GDES en ITER, en la que participaron el equipo y representantes del cliente, incluyendo un m\u00e1nager y un responsable de HSE. El evento incluy\u00f3 un taller pr\u00e1ctico y una comida compartida, como espacio de reconocimiento y refuerzo del compromiso con la seguridad.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-404356\" src=\"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/Arrecife-artficial-7.png\" alt=\"\" width=\"547\" height=\"325\" srcset=\"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/Arrecife-artficial-7.png 1080w, https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/Arrecife-artficial-7-300x178.png 300w, https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/Arrecife-artficial-7-1024x609.png 1024w, https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/Arrecife-artficial-7-768x457.png 768w\" sizes=\"(max-width: 547px) 100vw, 547px\" \/><\/p>\n<p>Durante el taller, de car\u00e1cter din\u00e1mico y participativo, se plante\u00f3 a los asistentes un caso basado en una situaci\u00f3n que podr\u00eda ser real, con el objetivo de poner en pr\u00e1ctica los principios de la cultura de seguridad. A partir de este escenario, los participantes trabajaron en la identificaci\u00f3n de peligros y riesgos, la definici\u00f3n de medidas de prevenci\u00f3n tanto colectivas como individuales, la selecci\u00f3n de los equipos de protecci\u00f3n adecuados entre distintas opciones, el establecimiento de balizamientos y la reflexi\u00f3n sobre buenas pr\u00e1cticas de almacenamiento y gesti\u00f3n de residuos. Todo ello permiti\u00f3 reforzar, de forma pr\u00e1ctica, la importancia de anticiparse a los riesgos y actuar de manera segura en el d\u00eda a d\u00eda.<\/p>\n<p>\u00a1Felicidades, equipo!<\/p>","protected":false},"excerpt":{"rendered":"<p>GDES celebr\u00f3 un hito muy significativo en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas. Un logro que reflej\u00f3 el compromiso diario del equipo con un objetivo constante: construir entornos de trabajo cada vez m\u00e1s seguros.<\/p>\n","protected":false},"author":3,"featured_media":404355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-404352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gdes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lucia Gomez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"GDES Corporate - Grupo Dominguis Energy Services -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate\" \/>\n\t\t<meta property=\"og:description\" content=\"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-09T13:30:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-09T13:45:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@GDES_news\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate\" \/>\n\t\t<meta name=\"twitter:description\" content=\"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@GDES_news\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#blogposting\",\"name\":\"GDES celebr\\u00f3 1000 d\\u00edas de trabajo seguro en ITER - GDES Corporate\",\"headline\":\"GDES celebr\\u00f3 1000 d\\u00edas de trabajo seguro en ITER\",\"author\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/author\\\/comesp\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/20260513_125429.jpg\",\"width\":2048,\"height\":1152},\"datePublished\":\"2026-06-09T14:30:49+01:00\",\"dateModified\":\"2026-06-09T14:45:57+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#webpage\"},\"articleSection\":\"Corporativo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/category\\\/gdes\\\/#listItem\",\"name\":\"Corporativo\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/category\\\/gdes\\\/#listItem\",\"position\":2,\"name\":\"Corporativo\",\"item\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/category\\\/gdes\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#listItem\",\"name\":\"GDES celebr\\u00f3 1000 d\\u00edas de trabajo seguro en ITER\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#listItem\",\"position\":3,\"name\":\"GDES celebr\\u00f3 1000 d\\u00edas de trabajo seguro en ITER\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/category\\\/gdes\\\/#listItem\",\"name\":\"Corporativo\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/#organization\",\"name\":\"GDES\",\"description\":\"Grupo Dominguis Energy Services\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/\",\"telephone\":\"+34963540300\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/08\\\/cropped-GDES-1.png\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#organizationLogo\",\"width\":115,\"height\":39},\"image\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/GDES_news\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gdes-grupo-dominguis-energy-services\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/author\\\/comesp\\\/#author\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/author\\\/comesp\\\/\",\"name\":\"Lucia Gomez\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#webpage\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/\",\"name\":\"GDES celebr\\u00f3 1000 d\\u00edas de trabajo seguro en ITER - GDES Corporate\",\"description\":\"GDES celebr\\u00f3 un hito en sus operaciones en ITER: 1000 d\\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\\u00e1s importante: las personas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/author\\\/comesp\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/author\\\/comesp\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/06\\\/20260513_125429.jpg\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#mainImage\",\"width\":2048,\"height\":1152},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/blog\\\/2026\\\/06\\\/09\\\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\\\/#mainImage\"},\"datePublished\":\"2026-06-09T14:30:49+01:00\",\"dateModified\":\"2026-06-09T14:45:57+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/\",\"name\":\"GDES Corporate\",\"description\":\"Grupo Dominguis Energy Services\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/gdes.com\\\/corporate\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate","description":"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.","canonical_url":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#blogposting","name":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate","headline":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER","author":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/author\/comesp\/#author"},"publisher":{"@id":"https:\/\/gdes.com\/corporate\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg","width":2048,"height":1152},"datePublished":"2026-06-09T14:30:49+01:00","dateModified":"2026-06-09T14:45:57+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#webpage"},"isPartOf":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#webpage"},"articleSection":"Corporativo"},{"@type":"BreadcrumbList","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es#listItem","position":1,"name":"Inicio","item":"https:\/\/gdes.com\/corporate\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/#listItem","name":"Corporativo"}},{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/#listItem","position":2,"name":"Corporativo","item":"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#listItem","name":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#listItem","position":3,"name":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER","previousItem":{"@type":"ListItem","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/#listItem","name":"Corporativo"}}]},{"@type":"Organization","@id":"https:\/\/gdes.com\/corporate\/es\/#organization","name":"GDES","description":"Grupo Dominguis Energy Services","url":"https:\/\/gdes.com\/corporate\/es\/","telephone":"+34963540300","logo":{"@type":"ImageObject","url":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2016\/08\/cropped-GDES-1.png","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#organizationLogo","width":115,"height":39},"image":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/GDES_news","https:\/\/www.linkedin.com\/company\/gdes-grupo-dominguis-energy-services"]},{"@type":"Person","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/author\/comesp\/#author","url":"https:\/\/gdes.com\/corporate\/es\/blog\/author\/comesp\/","name":"Lucia Gomez"},{"@type":"WebPage","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#webpage","url":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/","name":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate","description":"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/gdes.com\/corporate\/es\/#website"},"breadcrumb":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#breadcrumblist"},"author":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/author\/comesp\/#author"},"creator":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/author\/comesp\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg","@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#mainImage","width":2048,"height":1152},"primaryImageOfPage":{"@id":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/#mainImage"},"datePublished":"2026-06-09T14:30:49+01:00","dateModified":"2026-06-09T14:45:57+01:00"},{"@type":"WebSite","@id":"https:\/\/gdes.com\/corporate\/es\/#website","url":"https:\/\/gdes.com\/corporate\/es\/","name":"GDES Corporate","description":"Grupo Dominguis Energy Services","inLanguage":"es-ES","publisher":{"@id":"https:\/\/gdes.com\/corporate\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"GDES Corporate - Grupo Dominguis Energy Services -","og:type":"article","og:title":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate","og:description":"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.","og:url":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/","og:image":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg","og:image:secure_url":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg","og:image:width":2048,"og:image:height":1152,"article:published_time":"2026-06-09T13:30:49+00:00","article:modified_time":"2026-06-09T13:45:57+00:00","twitter:card":"summary_large_image","twitter:site":"@GDES_news","twitter:title":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER - GDES Corporate","twitter:description":"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.","twitter:creator":"@GDES_news","twitter:image":"https:\/\/gdes.com\/corporate\/wp-content\/uploads\/sites\/5\/2026\/06\/20260513_125429.jpg"},"aioseo_meta_data":{"post_id":"404352","title":null,"description":"GDES celebr\u00f3 un hito en sus operaciones en ITER: 1000 d\u00edas de trabajo seguro, en los que se ha puesto en el centro lo m\u00e1s importante: las personas.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-09 13:30:49","updated":"2026-06-09 14:02:13","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gdes.com\/corporate\/es\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&rsaquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/\" title=\"Corporativo\">Corporativo<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&rsaquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/gdes.com\/corporate\/es"},{"label":"Corporativo","link":"https:\/\/gdes.com\/corporate\/es\/blog\/category\/gdes\/"},{"label":"GDES celebr\u00f3 1000 d\u00edas de trabajo seguro en ITER","link":"https:\/\/gdes.com\/corporate\/es\/blog\/2026\/06\/09\/gdes-celebro-1000-dias-de-trabajo-seguro-en-iter\/"}],"_links":{"self":[{"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/posts\/404352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/comments?post=404352"}],"version-history":[{"count":3,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/posts\/404352\/revisions"}],"predecessor-version":[{"id":404368,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/posts\/404352\/revisions\/404368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/media\/404355"}],"wp:attachment":[{"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/media?parent=404352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/categories?post=404352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gdes.com\/corporate\/es\/wp-json\/wp\/v2\/tags?post=404352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}